{"id":6380,"date":"2021-01-22T20:56:45","date_gmt":"2021-01-23T01:56:45","guid":{"rendered":"https:\/\/copingspace.org\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/"},"modified":"2025-12-10T12:31:55","modified_gmt":"2025-12-10T17:31:55","slug":"la-experiencia-de-duelo-de-los-hermanos","status":"publish","type":"post","link":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/","title":{"rendered":"La experiencia de duelo de los hermanos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb3.22&#8243; background_color=\u00bbrgba(255,255,255,0)\u00bb custom_padding=\u00bb0px||0px|\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb][et_pb_fullwidth_header text_orientation=\u00bbcenter\u00bb image_orientation=\u00bbbottom\u00bb content_max_width=\u00bbnone\u00bb disabled_on=\u00bbon||\u00bb admin_label=\u00bbFullwidth Header &#8211; page title banner\u00bb module_class=\u00bbsub_page_header\u00bb _builder_version=\u00bb3.16&#8243; title_font=\u00bbLato|on|||\u00bb title_font_size=\u00bb32px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bb\/wp-content\/uploads\/2017\/02\/contact-banner1.jpg\u00bb title_font_size_tablet=\u00bb26px\u00bb title_font_size_phone=\u00bb20px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb custom_css_title=\u00bbtext-shadow: 1px 1p 1px rgba(0,0,0,0.9);\u00bb background_url=\u00bb\/wp-content\/uploads\/2017\/02\/contact-banner1.jpg\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; button_two_letter_spacing_hover=\u00bb0&#8243; saved_tabs=\u00bball\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb0&#8243; button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb0&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][et_pb_fullwidth_header text_orientation=\u00bbcenter\u00bb image_orientation=\u00bbbottom\u00bb content_max_width=\u00bbnone\u00bb disabled_on=\u00bboff|on|on\u00bb admin_label=\u00bbFullwidth Header &#8211; page title banner &#8211; mobile\u00bb module_class=\u00bbsub_page_header\u00bb _builder_version=\u00bb3.16&#8243; title_font=\u00bbLato|on|||\u00bb title_font_size=\u00bb32px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bb\/wp-content\/uploads\/2017\/02\/contact_mobile1.jpg\u00bb title_font_size_tablet=\u00bb26px\u00bb title_font_size_phone=\u00bb20px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb custom_css_title=\u00bbtext-shadow: 1px 1p 1px rgba(0,0,0,0.9);\u00bb background_url=\u00bb\/wp-content\/uploads\/2017\/02\/contact_mobile1.jpg\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; button_two_letter_spacing_hover=\u00bb0&#8243; saved_tabs=\u00bball\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb0&#8243; button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb0&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb3.22&#8243; background_color=\u00bbrgba(25,188,185,0.7)\u00bb custom_margin=\u00bb-40px||0px|\u00bb custom_padding=\u00bb0px||0px|\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb3.25&#8243; width=\u00bb100%\u00bb width_tablet=\u00bb100%\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb max_width_tablet=\u00bb100%\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb0px||0px|\u00bb custom_padding=\u00bb0px||0px|\u00bb make_fullwidth=\u00bbon\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb0px||0px|\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbBLOG HEADER\u00bb _builder_version=\u00bb3.27.4&#8243; text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb0px||0px|\u00bb custom_padding=\u00bb0px||0px|\u00bb header_text_shadow_style=\u00bbpreset2&#8243;]<\/p>\n<h1>BLOG<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb3.22&#8243;][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text content_tablet=\u00bb\u00bb content_phone=\u00bb\u00bb content_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.8.1&#8243;]<\/p>\n<h1>Encontrar las palabras cuando no hay nada que decir: la experiencia de duelo de los hermanos<\/h1>\n<p>Lynn Shattuck \/ 23 de enero de 2021<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-942 size-medium\" src=\"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg\" alt=\"Grieving sibling\" width=\"300\" height=\"200\" srcset=\"https:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg 300w, https:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Estaba navegando por Facebook el otro d\u00eda cuando me encontr\u00e9 con esta pregunta en una p\u00e1gina que sigo: <em>\u00bfQu\u00e9 es lo \u00fanico que te hubiera gustado o\u00edr despu\u00e9s de la muerte de tu hermano o hermana?<\/em> <\/p>\n<p>Pens\u00e9 en la pregunta durante un d\u00eda completo, dej\u00e1ndola resonar en el fondo de mi mente. Pas\u00e9 mucho tiempo considerando todas las cosas que desear\u00eda que la gente <em>no<\/em> me hubiera dicho cuando mi hermano muri\u00f3, como: \u201cs\u00e9 fuerte para tus padres\u201d o, \u201cpor favor, dile a tu mam\u00e1 cu\u00e1nto lo siento, \u00bfc\u00f3mo est\u00e1 <em>ella<\/em>?\u201d<\/p>\n<p>Es duro profundizar m\u00e1s y encontrar las palabras que podr\u00edan haberme ayudado en esos d\u00edas crudos despu\u00e9s de la muerte de mi hermano. Como escritora y gran lectora, valoro mucho el poder de las palabras, pero no estoy segura de que las palabras tengan suficiente magia como para calmar la pena de un duelo reciente.<\/p>\n<h2>Aflicci\u00f3n por la muerte de un hermano<\/h2>\n<p>Ten\u00eda 24&nbsp;a\u00f1os cuando mi hermano Will muri\u00f3. \u00c9l ten\u00eda 21. Han pasado m\u00e1s de 20&nbsp;a\u00f1os, pero constru\u00ed una vida alrededor de mi aflicci\u00f3n. En los primeros d\u00edas y meses, no pod\u00eda imaginar c\u00f3mo sobrevivir\u00eda. El dolor de perder a mi hermano era m\u00e1s intenso que cualquier cosa que hubiera sentido antes. Mi p\u00e9rdida fue f\u00edsica, un latido profundo en el pecho, un remolino de p\u00e1nico en el vientre que solo se calmaba despu\u00e9s de un buen llanto.<\/p>\n<p>No hab\u00eda nada que pudiera hacer para aliviarlo, excepto tal vez el lento paso del tiempo.<\/p>\n<p><strong>La soledad por la muerte de mi hermano era abrumadora. <\/strong>Mi hermano hab\u00eda sido mi rival, una plaga, el guardi\u00e1n de mi infancia, y cuando salimos de la adolescencia, finalmente mi amigo. Se supon\u00eda que ten\u00edamos que vivir juntos. Mis amigos me apoyaron, pero tambi\u00e9n eran adultos j\u00f3venes, inmersos en las cosas que hacen los adultos j\u00f3venes: salir, viajar, ir a la escuela, trabajar, vivir sus vidas.<\/p>\n<p>Mi vida, en cambio, estaba interrumpida, me hab\u00eda mudado de vuelta a casa sin perspectivas rom\u00e1nticas ni profesionales en el horizonte. Mis padres estaban sufriendo incre\u00edblemente y la \u00fanica otra persona que pod\u00eda entender lo que yo sent\u00eda al ver su agon\u00eda era mi hermano, cuya muerte hab\u00eda provocado ese dolor.<\/p>\n<h2>C\u00f3mo ayudar a alguien que ha perdido a un hermano<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-957 size-medium\" src=\"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/siblingscope-300x200.jpg\" alt=\"Women hugging\" width=\"300\" height=\"200\" srcset=\"https:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/siblingscope-300x200.jpg 300w, https:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/siblingscope.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Tal vez no haya palabras adecuadas para la muerta de esa persona indispensable en tu vida. <strong>En retrospectiva, creo que simples reconocimientos podr\u00edan haber ayudado.<\/strong> A los hermanos se les conoce como los dolientes invisibles u olvidados. Ahora que soy madre puedo entender por qu\u00e9 la gente se centr\u00f3 principalmente en mis padres despu\u00e9s de que mi hermano muri\u00f3. Perder a un hijo es terrible, y algo que ning\u00fan padre deber\u00eda tener que soportar. Pero perder a un hermano o hermana tambi\u00e9n es incre\u00edblemente impactante. Mis padres, despu\u00e9s de todo, todav\u00eda eran padres; yo me preguntaba si segu\u00eda siendo hermana ahora que mi \u00fanico hermano se hab\u00eda ido.<\/p>\n<p>En la \u00e9poca en que Will muri\u00f3, ni siquiera hab\u00eda libros sobre el tema de la p\u00e9rdida de hermanos adultos. Escuchar cosas como \u201cesto debe ser tan dif\u00edcil\u201d me habr\u00eda ayudado o, al menos, no habr\u00eda hecho da\u00f1o. Un amigo sensible me dijo \u201ccreo que me volver\u00eda loco si algo le sucediera a mi hermano\u201d. Sus palabras me calmaron, porque estaban empapadas de empat\u00eda pura en lugar de lugares comunes. Me hicieron sentir menos invisible, menos sola.<\/p>\n<h2>P\u00e9rdida de hermanos: la p\u00e9rdida de la vida<\/h2>\n<p>El lugar donde existi\u00f3 Will permanece, siempre estar\u00e1 all\u00ed. Nunca dejar\u00e9 de desear que estuviera aqu\u00ed o de preguntarme qu\u00e9 tipo de t\u00edo ser\u00eda para mis hijos. Cuando mi padre muri\u00f3 el verano pasado, tambi\u00e9n me aflig\u00ed por mi hermano. \u00c9l deber\u00eda haber estado all\u00ed, transitando este triste momento conmigo.<\/p>\n<p>Como amante de las palabras, podr\u00eda haberle buscado un nombre a lo que experiment\u00e9 despu\u00e9s de la muerte de Will. Cuando perdemos a nuestros padres, somos hu\u00e9rfanos. Cuando un c\u00f3nyuge muere, somos viudos. \u201cHermano en duelo\u201d suena tan cl\u00ednico, tan formal, tan diferente a la relaci\u00f3n que la mayor\u00eda de nosotros experimentamos con nuestros hermanos o hermanas. <strong>He llamado a la p\u00e9rdida de un hermano, \u201cla p\u00e9rdida de la vida\u201d.<\/strong> Cuando una hermana o un hermano muere, perdemos nuestra conexi\u00f3n con el pasado y con el futuro que pensamos que tendr\u00edamos juntos. \u00bfCon qui\u00e9n m\u00e1s esperamos pasar toda nuestra vida, sino con nuestros hermanos?<\/p>\n<p>Tal vez esa frase hubiera sido algo a lo que aferrarse durante la soledad m\u00e1s intensa de mi dolor. O esto: <em>vas a salir de esta, pero no lo superar\u00e1s. Te doler\u00e1 para siempre, pero aprender\u00e1s a vivir con el dolor.<\/em> <em>Tu aflicci\u00f3n es amor, expuesto hacia el exterior, se plegar\u00e1 y se quedar\u00e1 contigo toda la vida\u2026 como tu hermano deber\u00eda haberlo hecho.<\/em><\/p>\n<hr\/>\n<p><strong>Sobre el autor:<\/strong> Lynn Shattuck creci\u00f3 en una selva tropical del sureste de Alaska y ahora, es una escritora que vive en Maine. En este momento, Lynn est\u00e1 trabajando en un libro de memorias sobre la muerte de su hermano. Para leer m\u00e1s de su trabajo, visita su sitio web en <a href=\"http:\/\/thelightwillfindyou.com\/\">http:\/\/thelightwillfindyou.com\/<\/a> o suscr\u00edbete a su <a href=\"https:\/\/mailchi.mp\/1340d8f6f016\/sign-up-for-my-mailing-list?fbclid=IwAR2gXgDAEc-pZwO8__4rWyCxd3lABTwAKyVAVf1xfKawE0P7V1v5rMX16Rk\">lista de correo<\/a>.<\/p>\n<p>**<em>Las declaraciones en este blog reflejan la opini\u00f3n personal del autor y no representan las opiniones de Ryan&#8217;s Case for Smiles. Tampoco deben interpretarse como un consejo m\u00e9dico personal, sino m\u00e1s bien con el prop\u00f3sito de aportar conocimiento general. El lector debe hablar con su equipo de atenci\u00f3n m\u00e9dica, o con el de su hijo, para obtener asesoramiento m\u00e9dico.<\/em>**<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_sidebar orientation=\u00bbright\u00bb area=\u00bbsidebar-1&#8243; _builder_version=\u00bb3.0.100&#8243;][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BLOGEncontrar las palabras cuando no hay nada que decir: la experiencia de duelo de los hermanos Lynn Shattuck \/ 23 de enero de 2021 Estaba navegando por Facebook el otro d\u00eda cuando me encontr\u00e9 con esta pregunta en una p\u00e1gina que sigo: \u00bfQu\u00e9 es lo \u00fanico que te hubiera gustado o\u00edr despu\u00e9s de la muerte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[22,15],"tags":[],"class_list":["post-6380","post","type-post","status-publish","format-standard","hentry","category-blog","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La experiencia de duelo de los hermanos - Coping Space<\/title>\n<meta name=\"description\" content=\"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La experiencia de duelo de los hermanos - Coping Space\" \/>\n<meta property=\"og:description\" content=\"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Coping Space\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-23T01:56:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T17:31:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg\" \/>\n<meta name=\"author\" content=\"cfrisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfrisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/\"},\"author\":{\"name\":\"cfrisco\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/#\\\/schema\\\/person\\\/01e50c3c0fe872094c6146f3f0077c82\"},\"headline\":\"La experiencia de duelo de los hermanos\",\"datePublished\":\"2021-01-23T01:56:45+00:00\",\"dateModified\":\"2025-12-10T17:31:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/\"},\"wordCount\":1693,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/copingspace.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/consoling_teen-300x200.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/\",\"url\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/\",\"name\":\"La experiencia de duelo de los hermanos - Coping Space\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/copingspace.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/consoling_teen-300x200.jpg\",\"datePublished\":\"2021-01-23T01:56:45+00:00\",\"dateModified\":\"2025-12-10T17:31:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/#\\\/schema\\\/person\\\/01e50c3c0fe872094c6146f3f0077c82\"},\"description\":\"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#primaryimage\",\"url\":\"http:\\\/\\\/copingspace.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/consoling_teen-300x200.jpg\",\"contentUrl\":\"http:\\\/\\\/copingspace.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/consoling_teen-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/2021\\\/01\\\/22\\\/la-experiencia-de-duelo-de-los-hermanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copingspace.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La experiencia de duelo de los hermanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/copingspace.org\\\/es\\\/\",\"name\":\"Coping Space\",\"description\":\"Case For Smiles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copingspace.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/copingspace.org\\\/es\\\/#\\\/schema\\\/person\\\/01e50c3c0fe872094c6146f3f0077c82\",\"name\":\"cfrisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g\",\"caption\":\"cfrisco\"},\"url\":\"https:\\\/\\\/copingspace.org\\\/es\\\/author\\\/cfrisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La experiencia de duelo de los hermanos - Coping Space","description":"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/","og_locale":"es_ES","og_type":"article","og_title":"La experiencia de duelo de los hermanos - Coping Space","og_description":"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.","og_url":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/","og_site_name":"Coping Space","article_published_time":"2021-01-23T01:56:45+00:00","article_modified_time":"2025-12-10T17:31:55+00:00","og_image":[{"url":"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg","type":"","width":"","height":""}],"author":"cfrisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cfrisco","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#article","isPartOf":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/"},"author":{"name":"cfrisco","@id":"https:\/\/copingspace.org\/es\/#\/schema\/person\/01e50c3c0fe872094c6146f3f0077c82"},"headline":"La experiencia de duelo de los hermanos","datePublished":"2021-01-23T01:56:45+00:00","dateModified":"2025-12-10T17:31:55+00:00","mainEntityOfPage":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/"},"wordCount":1693,"commentCount":0,"image":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#primaryimage"},"thumbnailUrl":"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg","articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/","url":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/","name":"La experiencia de duelo de los hermanos - Coping Space","isPartOf":{"@id":"https:\/\/copingspace.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#primaryimage"},"image":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#primaryimage"},"thumbnailUrl":"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg","datePublished":"2021-01-23T01:56:45+00:00","dateModified":"2025-12-10T17:31:55+00:00","author":{"@id":"https:\/\/copingspace.org\/es\/#\/schema\/person\/01e50c3c0fe872094c6146f3f0077c82"},"description":"El duelo por la muerte de un hermano es un proceso doloroso, pero la aflicci\u00f3n de los hermanos no siempre es bien comprendida. Sigue leyendo para aprender m\u00e1s sobre esto y c\u00f3mo ayudar.","breadcrumb":{"@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#primaryimage","url":"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg","contentUrl":"http:\/\/copingspace.org\/wp-content\/uploads\/2017\/01\/consoling_teen-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/copingspace.org\/es\/2021\/01\/22\/la-experiencia-de-duelo-de-los-hermanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copingspace.org\/es\/"},{"@type":"ListItem","position":2,"name":"La experiencia de duelo de los hermanos"}]},{"@type":"WebSite","@id":"https:\/\/copingspace.org\/es\/#website","url":"https:\/\/copingspace.org\/es\/","name":"Coping Space","description":"Case For Smiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copingspace.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/copingspace.org\/es\/#\/schema\/person\/01e50c3c0fe872094c6146f3f0077c82","name":"cfrisco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1dd581895e681c02dca5fd01f2f7de51a1652a07d6cb6f0c741efe0000f3e53?s=96&d=mm&r=g","caption":"cfrisco"},"url":"https:\/\/copingspace.org\/es\/author\/cfrisco\/"}]}},"_links":{"self":[{"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/posts\/6380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/comments?post=6380"}],"version-history":[{"count":1,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/posts\/6380\/revisions"}],"predecessor-version":[{"id":6398,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/posts\/6380\/revisions\/6398"}],"wp:attachment":[{"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/media?parent=6380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/categories?post=6380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/copingspace.org\/es\/wp-json\/wp\/v2\/tags?post=6380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}